{"id":3529,"date":"2018-03-19T21:05:28","date_gmt":"2018-03-19T18:05:28","guid":{"rendered":"https:\/\/www.visioneyes.ro\/?post_type=product&#038;p=3529"},"modified":"2018-03-19T21:05:28","modified_gmt":"2018-03-19T18:05:28","slug":"vogue-ovo4066-5060","status":"publish","type":"product","link":"https:\/\/www.visioneyes.ro\/en\/shop-online\/vogue-ovo4066-5060\/","title":{"rendered":"Vogue OVO4066 5060"},"content":{"rendered":"<p class=\"pro-subtitle\">Technical Specifications<\/p>\n<ul class=\"infor-specification-list\">\n<li>Brand: Vogue Eyewear<\/li>\n<li>Gender: Women<\/li>\n<li class=\"pro_t_lidis\">Year: 2017<\/li>\n<li>Frame Color: Dark Red\/Gold<\/li>\n<li>Frame Shape: Oval<\/li>\n<li class=\"pro_t_lidis\">Frame Style: Full Rim<\/li>\n<li>Frame Material: Metal<\/li>\n<li class=\"pro_t_lidis\">Lens Material: Customisable<\/li>\n<\/ul>\n<p>Description<\/p>\n<p>Vogue Eyewear VO4066 glasses come with a sturdy Metal frame. The SmartBuyGlasses prescription lenses option is a great choice so your eyeglasses arrive on your doorstep ready to wear. Our lenses are coated with a special advanced coating which renders them anti-glare and scratch resistant. The Vogue Eyewear VO4066 eyeglasses feature a Dark Red\/Gold frame and standard lenses. To top it off you also have a 2 year warranty.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technical Specifications Brand: Vogue Eyewear Gender: Women Year: 2017 Frame Color: Dark Red\/Gold Frame Shape: Oval Frame Style: Full Rim Frame Material: Metal Lens Material: Customisable Description Vogue Eyewear VO4066 glasses come with a sturdy Metal frame. The SmartBuyGlasses prescription lenses option is a great choice so your eyeglasses arrive on your doorstep ready to [&#8230;]\n","protected":false},"featured_media":3530,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vogue OVO4066 5060 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vogue OVO4066 5060 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\" \/>\n<meta property=\"og:description\" content=\"Technical Specifications Brand: Vogue Eyewear Gender: Women Year: 2017 Frame Color: Dark Red\/Gold Frame Shape: Oval Frame Style: Full Rim Frame Material: Metal Lens Material: Customisable Description Vogue Eyewear VO4066 glasses come with a sturdy Metal frame. The SmartBuyGlasses prescription lenses option is a great choice so your eyeglasses arrive on your doorstep ready to [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/\" \/>\n<meta property=\"og:site_name\" content=\"Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visioneyes.ro\/wp-content\/uploads\/Vogue-Eyewear-VO4066-5060.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.visioneyes.ro\/#website\",\"url\":\"https:\/\/www.visioneyes.ro\/\",\"name\":\"Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.visioneyes.ro\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.visioneyes.ro\/wp-content\/uploads\/Vogue-Eyewear-VO4066-5060.jpg\",\"width\":600,\"height\":300},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/#webpage\",\"url\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/\",\"name\":\"Vogue OVO4066 5060 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\",\"isPartOf\":{\"@id\":\"https:\/\/www.visioneyes.ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/#primaryimage\"},\"datePublished\":\"2018-03-19T18:05:28+00:00\",\"dateModified\":\"2018-03-19T18:05:28+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-ovo4066-5060\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/product\/3529"}],"collection":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/comments?post=3529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/media\/3530"}],"wp:attachment":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/media?parent=3529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}