{"id":3613,"date":"2018-03-21T20:17:40","date_gmt":"2018-03-21T17:17:40","guid":{"rendered":"https:\/\/www.visioneyes.ro\/?post_type=product&#038;p=3613"},"modified":"2019-02-07T14:47:48","modified_gmt":"2019-02-07T11:47:48","slug":"vogue-vo4086-848","status":"publish","type":"product","link":"https:\/\/www.visioneyes.ro\/en\/shop-online\/vogue-vo4086-848\/","title":{"rendered":"Vogue VO4086 848"},"content":{"rendered":"<p><span class=\"prd-attribute-list\">Product Code:<\/span> 4086\/848<br \/>\n<span class=\"prd-attribute-list\">Size:<\/span> (48-20-135)<br \/>\n<span class=\"prd-attribute-list\">Style:<\/span> Full Frame<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Product Code: 4086\/848 Size: (48-20-135) Style: Full Frame<\/p>\n","protected":false},"featured_media":3614,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vogue VO4086 848 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vogue VO4086 848 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\" \/>\n<meta property=\"og:description\" content=\"Product Code: 4086\/848 Size: (48-20-135) Style: Full Frame\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/\" \/>\n<meta property=\"og:site_name\" content=\"Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-07T11:47:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visioneyes.ro\/wp-content\/uploads\/vogue-vo-4086-848-eyeglasses-01-732x549.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"732\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.visioneyes.ro\/#website\",\"url\":\"https:\/\/www.visioneyes.ro\/\",\"name\":\"Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.visioneyes.ro\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.visioneyes.ro\/wp-content\/uploads\/vogue-vo-4086-848-eyeglasses-01-732x549.jpg\",\"width\":732,\"height\":549},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/#webpage\",\"url\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/\",\"name\":\"Vogue VO4086 848 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\",\"isPartOf\":{\"@id\":\"https:\/\/www.visioneyes.ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/#primaryimage\"},\"datePublished\":\"2018-03-21T17:17:40+00:00\",\"dateModified\":\"2019-02-07T11:47:48+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo4086-848\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/product\/3613"}],"collection":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/comments?post=3613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/media\/3614"}],"wp:attachment":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/media?parent=3613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}