{"id":3628,"date":"2018-03-21T20:45:05","date_gmt":"2018-03-21T18:45:05","guid":{"rendered":"https:\/\/www.visioneyes.ro\/?post_type=product&#038;p=3628"},"modified":"2025-02-13T11:38:55","modified_gmt":"2025-02-13T09:38:55","slug":"vogue-vo5057-w44","status":"publish","type":"product","link":"https:\/\/www.visioneyes.ro\/en\/shop-online\/vogue-vo5057-w44\/","title":{"rendered":"Vogue VO5057 W44"},"content":{"rendered":"<p class=\"pro-subtitle\">Technical Specifications<\/p>\n<ul class=\"infor-specification-list\">\n<li>Brand: Vogue Eyewear<\/li>\n<li>Gender: Women<\/li>\n<li class=\"pro_t_lidis\">Year: 2016<\/li>\n<li>Frame Color: Black<\/li>\n<li>Frame Shape: Cat Eye<\/li>\n<li class=\"pro_t_lidis\">Frame Style: Full Rim<\/li>\n<li>Frame Material: Plastic<\/li>\n<li class=\"pro_t_lidis\">Lens Material: Customisable<\/li>\n<\/ul>\n<p>Description<\/p>\n<p>The Vogue Eyewear eyeglasses collection includes a wide range of attractive styles. The Vogue Eyewear VO5057F Asian Fit frame is made of Plastic and comes in a range of stylish colors. Optional prescription lenses, fitted by our in-house professionals can be included at a fantastic price, meaning that your glasses are ready to go as soon as they arrive, no trips to the optometrist required!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technical Specifications Brand: Vogue Eyewear Gender: Women Year: 2016 Frame Color: Black Frame Shape: Cat Eye Frame Style: Full Rim Frame Material: Plastic Lens Material: Customisable Description The Vogue Eyewear eyeglasses collection includes a wide range of attractive styles. The Vogue Eyewear VO5057F Asian Fit frame is made of Plastic and comes in a range [&#8230;]\n","protected":false},"featured_media":3629,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vogue VO5057 W44 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vogue VO5057 W44 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\" \/>\n<meta property=\"og:description\" content=\"Technical Specifications Brand: Vogue Eyewear Gender: Women Year: 2016 Frame Color: Black Frame Shape: Cat Eye Frame Style: Full Rim Frame Material: Plastic Lens Material: Customisable Description The Vogue Eyewear eyeglasses collection includes a wide range of attractive styles. The Vogue Eyewear VO5057F Asian Fit frame is made of Plastic and comes in a range [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/\" \/>\n<meta property=\"og:site_name\" content=\"Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T09:38:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visioneyes.ro\/wp-content\/uploads\/Vogue-Eyewear-VO5057F-Asian-Fit-W44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.visioneyes.ro\/#website\",\"url\":\"https:\/\/www.visioneyes.ro\/\",\"name\":\"Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.visioneyes.ro\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.visioneyes.ro\/wp-content\/uploads\/Vogue-Eyewear-VO5057F-Asian-Fit-W44.jpg\",\"width\":600,\"height\":300},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/#webpage\",\"url\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/\",\"name\":\"Vogue VO5057 W44 - Sun glasses, Contact Lenses, Eye glasses, Eyeglass Frames | VisionEyes\",\"isPartOf\":{\"@id\":\"https:\/\/www.visioneyes.ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/#primaryimage\"},\"datePublished\":\"2018-03-21T18:45:05+00:00\",\"dateModified\":\"2025-02-13T09:38:55+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.visioneyes.ro\/shop-online\/vogue-vo5057-w44\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/product\/3628"}],"collection":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/comments?post=3628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/media\/3629"}],"wp:attachment":[{"href":"https:\/\/www.visioneyes.ro\/en\/wp-json\/wp\/v2\/media?parent=3628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}